{"id":808,"date":"2023-06-12T17:37:09","date_gmt":"2023-06-12T10:37:09","guid":{"rendered":"https:\/\/www.thaiprintawards.com\/tp2023\/?page_id=808"},"modified":"2023-10-02T17:12:13","modified_gmt":"2023-10-02T10:12:13","slug":"digital-printing-only","status":"publish","type":"page","link":"https:\/\/www.thaiprintawards.com\/tp2023\/awards-winners\/digital-printing-only\/","title":{"rendered":"Digital Printing Only"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;1527&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;15%&#8221; top_padding_tablet=&#8221;20%&#8221; top_padding_phone=&#8221;20%&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;10&#8243; overflow=&#8221;hidden&#8221; enable_gradient=&#8221;true&#8221; color_overlay=&#8221;#318fff&#8221; color_overlay_2=&#8221;#2fc9fc&#8221; advanced_gradient_angle=&#8221;183&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_b_to_right_t&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;zoom-out-slow&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; zindex=&#8221;10&#8243; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5px&#8221; top_padding_tablet=&#8221;5px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;5px&#8221; top_padding_phone=&#8221;3px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;3px&#8221; translate_x=&#8221;-13%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;2.5&#8243; persist_movement_on_mobile=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;ltr&#8221; scroll_speed=&#8221;slower&#8221; text_color=&#8221;#ffffff&#8221; style=&#8221;default&#8221; text_repeat_number=&#8221;5&#8243; text_repeat_divider=&#8221;space&#8221; text_space_amount=&#8221;large&#8221; overflow=&#8221;visible&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;5vw&#8221; custom_font_size_mobile=&#8221;5vw&#8221;]\n<h1 style=\"text-shadow: 1px 1px 4px #333333;\">Digital Printing Only<\/h1>\n[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;5px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5px&#8221; top_padding_tablet=&#8221;5px&#8221; constrain_group_3=&#8221;yes&#8221; bottom_padding_tablet=&#8221;5px&#8221; top_padding_phone=&#8221;3px&#8221; constrain_group_5=&#8221;yes&#8221; bottom_padding_phone=&#8221;3px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;parallax&#8221; animation_movement_type=&#8221;transform_x&#8221; column_parallax_intensity=&#8221;-2.5&#8243; persist_movement_on_mobile=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_scrolling_text scroll_direction=&#8221;rtl&#8221; scroll_speed=&#8221;slower&#8221; text_color=&#8221;#ffffff&#8221; style=&#8221;default&#8221; text_repeat_number=&#8221;5&#8243; text_repeat_divider=&#8221;space&#8221; text_space_amount=&#8221;large&#8221; overflow=&#8221;visible&#8221; background_image_animation=&#8221;None&#8221; custom_font_size=&#8221;5vw&#8221; custom_font_size_mobile=&#8221;5vw&#8221;]\n<h1 style=\"text-shadow: 1px 1px 4px #333333;\">Digital Printing Only<\/h1>\n[\/nectar_scrolling_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;-25vw&#8221; top_margin_tablet=&#8221;-28vw&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; column_padding_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;1539&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Bottom&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;skip-lazy-load&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_color=&#8221;#9ebee7&#8243; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;200px&#8221; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30px&#8221; custom_height_tablet=&#8221;30px&#8221; custom_height_phone=&#8221;30px&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30px&#8221; custom_height_tablet=&#8221;30px&#8221; custom_height_phone=&#8221;30px&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;center&#8221; mobile_content_alignment=&#8221;center&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Digital Printing Only&#8221; font_size=&#8221;2vw&#8221; font_size_tablet=&#8221;4vw&#8221; font_size_phone=&#8221;6vw&#8221;][\/split_line_heading][vc_column_text css_animation=&#8221;fadeInUp&#8221;]\n<h3 style=\"text-align: center;\">\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e41\u0e1a\u0e1a\u0e14\u0e34\u0e08\u0e34\u0e15\u0e2d\u0e25\u0e44\u0e21\u0e48\u0e08\u0e33\u0e01\u0e31\u0e14\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a<\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30px&#8221; custom_height_tablet=&#8221;30px&#8221; custom_height_phone=&#8221;30px&#8221;][nectar_post_grid post_type=&#8221;portfolio&#8221; portfolio_category=&#8221;digital-printing-only&#8221; order=&#8221;ASC&#8221; orderby=&#8221;date&#8221; pagination=&#8221;load-more&#8221; button_color=&#8221;black&#8221; columns=&#8221;3&#8243; grid_item_spacing=&#8221;10px&#8221; grid_item_height=&#8221;50vh&#8221; image_size=&#8221;full&#8221; image_loading=&#8221;default&#8221; animation=&#8221;fade-in-from-bottom&#8221; heading_tag=&#8221;h3&#8243; enable_indicator=&#8221;yes&#8221; mouse_indicator_style=&#8221;default&#8221; mouse_indicator_text=&#8221;view&#8221; mouse_indicator_color=&#8221;#318fff&#8221; category_position=&#8221;default&#8221; grid_style=&#8221;content_overlaid&#8221; text_content_layout=&#8221;all_bottom_left_shadow&#8221; color_overlay=&#8221;#999999&#8243; color_overlay_opacity=&#8221;0&#8243; color_overlay_hover_opacity=&#8221;0.5&#8243; text_color=&#8221;light&#8221; text_color_hover=&#8221;light&#8221; text_opacity=&#8221;1&#8243; text_hover_opacity=&#8221;1&#8243; hover_effect=&#8221;zoom&#8221; border_radius=&#8221;none&#8221; shadow_on_hover=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;top&#8221; shape_divider_height=&#8221;20%&#8221; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves_opacity&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;183&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;top&#8221; shape_divider_height=&#8221;20%&#8221; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;waves_opacity&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;106&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":34,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/pages\/808"}],"collection":[{"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/comments?post=808"}],"version-history":[{"count":2,"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/pages\/808\/revisions"}],"predecessor-version":[{"id":1978,"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/pages\/808\/revisions\/1978"}],"up":[{"embeddable":true,"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/pages\/34"}],"wp:attachment":[{"href":"https:\/\/www.thaiprintawards.com\/tp2023\/wp-json\/wp\/v2\/media?parent=808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}